{"id":83578,"date":"2022-10-25T13:33:00","date_gmt":"2022-10-25T12:33:00","guid":{"rendered":"https:\/\/www.perceptual-robotics.com\/?p=83578"},"modified":"2022-10-25T13:33:00","modified_gmt":"2022-10-25T12:33:00","slug":"perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion","status":"publish","type":"post","link":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/","title":{"rendered":"Perceptual Robotics ofrece una visi\u00f3n excepcional de sus capacidades de inspecci\u00f3n"},"content":{"rendered":"<p>Perceptual Robotics ha brindado a la industria de inspecciones y mantenimiento e\u00f3licas una visi\u00f3n \u00fanica de sus capacidades al realizar unas demostraciones exclusivas con socios potenciales.<\/p>\n<p>La compa\u00f1\u00eda, que tiene oficinas en el Reino Unido y Europa, dio la bienvenida a ocho empresas de toda Espa\u00f1a para que participaran en su d\u00eda de demostraci\u00f3n en el Parque E\u00f3lico Experimental Sotavento en Lugo, Espa\u00f1a.<\/p>\n<p>Los ingenieros de Perceptual Robotics volaron un dron M300 y utilizaron su exclusivo sistema Dhalion para inspeccionar de forma aut\u00f3noma una turbina e\u00f3lica G47 el 18 de octubre.<\/p>\n<p>Se realizaron dos demostraciones en las que los asistentes pudieron ver en persona y en detalle el sistema Dhalion, as\u00ed como la realizaci\u00f3n de una inspecci\u00f3n en tiempo real. Despu\u00e9s del vuelo pudieron comprobar c\u00f3mo se realiza el procesamiento de datos y c\u00f3mo se presentan y analizan las im\u00e1genes y los resultados de inspecci\u00f3n en el portal web del sistema.<\/p>\n<p>Kostas Karachalios, CEO de Perceptual Robotics, declar\u00f3: \u201cEsta ha sido una excelente oportunidad para que diferentes actores de la industria vieran de cerca c\u00f3mo funciona nuestro sistema en condiciones operativas reales. Asistieron personas de todos los \u00e1mbitos e\u00f3licos, desde propietarios de activos y utilities hasta compa\u00f1\u00edas de drones y empresas de servicios de inspecci\u00f3n y reparaci\u00f3n. Al compartir nuestra amplia experiencia en la inspecci\u00f3n de estas grandes estructuras, podemos generar el cambio que la industria necesita para que las inspecciones sean m\u00e1s rentables, r\u00e1pidas y seguras para todos\u201d.<\/p>\n<p>El sistema Dhalion de Perceptual Robotics est\u00e1 dise\u00f1ado para realizar inspecciones aut\u00f3nomas en profundidad de turbinas, recopilar datos de alta calidad en menos de 20 minutos y analizar r\u00e1pidamente los datos recopilados mediante el procesado de im\u00e1genes con Inteligencia Artificial de \u00faltima generaci\u00f3n.<\/p>\n<p>A principios de este a\u00f1o, la compa\u00f1\u00eda anunci\u00f3 que sus sistemas y su inteligencia artificial hab\u00edan demostrado ser casi un 15 % m\u00e1s precisos en la detecci\u00f3n de da\u00f1os en los aerogeneradores gracias a un proyecto de investigaci\u00f3n y desarrollo de Innovate UK, realizado en colaboraci\u00f3n con la Universidad de Bristol. El proyecto mostr\u00f3 que el sistema \u00fanico de los socios ten\u00eda una mejora del 14 % en la precisi\u00f3n de detecci\u00f3n de da\u00f1os en comparaci\u00f3n con humanos expertos que realizaban las mismas inspecciones.<\/p>\n<p>Estos d\u00edas de demostraci\u00f3n de Perceptual Robotics son los primeros de muchos. La empresa pide a los interesados \u200b\u200ben conocer el sistema de primera mano que se pongan en contacto para concertar una reuni\u00f3n.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre Perceptual Robotics y sus soluciones para la industria de inspecci\u00f3n y mantenimiento, visite www.perceptual-robotics.com\/es<\/p>\n<p>&nbsp;<\/p>\n<div style=\"width: 840px;\" class=\"wp-video\"><video data-keepplaying class=\"wp-video-shortcode\" id=\"video-83578-1\" width=\"840\" height=\"473\" poster=\"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Thumbnail-for-videos-21.10.22-e1666363609594.jpg\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Demo-Spain.mp4?_=1\" \/><a href=\"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Demo-Spain.mp4\">https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Demo-Spain.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Perceptual Robotics ha brindado a la industria de inspecciones y mantenimiento e\u00f3licas una visi\u00f3n \u00fanica de sus capacidades al realizar unas demostraciones exclusivas con socios potenciales.<\/p>\n","protected":false},"author":7,"featured_media":83473,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[47],"tags":[62,68,57,58],"class_list":["post-83578","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-sin-categorizar","tag-ai-es","tag-innovation-es","tag-renewableenergy-es","tag-windenergy-es","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Perceptual Robotics ofrece una visi\u00f3n excepcional de sus capacidades de inspecci\u00f3n - Perceptual Robotics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perceptual Robotics ofrece una visi\u00f3n excepcional de sus capacidades de inspecci\u00f3n - Perceptual Robotics\" \/>\n<meta property=\"og:description\" content=\"Perceptual Robotics ha brindado a la industria de inspecciones y mantenimiento e\u00f3licas una visi\u00f3n \u00fanica de sus capacidades al realizar unas demostraciones exclusivas con socios potenciales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Perceptual Robotics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/perceptualrobotics\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T12:33:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Thumbnail-for-videos-21.10.22-e1666363609594.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1053\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irenie Karachaliou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Perc_Robotics\" \/>\n<meta name=\"twitter:site\" content=\"@Perc_Robotics\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irenie Karachaliou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perceptual Robotics ofrece una visi\u00f3n excepcional de sus capacidades de inspecci\u00f3n - Perceptual Robotics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/","og_locale":"es_ES","og_type":"article","og_title":"Perceptual Robotics ofrece una visi\u00f3n excepcional de sus capacidades de inspecci\u00f3n - Perceptual Robotics","og_description":"Perceptual Robotics ha brindado a la industria de inspecciones y mantenimiento e\u00f3licas una visi\u00f3n \u00fanica de sus capacidades al realizar unas demostraciones exclusivas con socios potenciales.","og_url":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/","og_site_name":"Perceptual Robotics","article_publisher":"https:\/\/www.facebook.com\/perceptualrobotics\/","article_published_time":"2022-10-25T12:33:00+00:00","og_image":[{"width":1053,"height":601,"url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Thumbnail-for-videos-21.10.22-e1666363609594.jpg","type":"image\/jpeg"}],"author":"Irenie Karachaliou","twitter_card":"summary_large_image","twitter_creator":"@Perc_Robotics","twitter_site":"@Perc_Robotics","twitter_misc":{"Escrito por":"Irenie Karachaliou","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/#article","isPartOf":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/"},"author":{"name":"Irenie Karachaliou","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/person\/fd287a03747dd732641469d987ba62f7"},"headline":"Perceptual Robotics ofrece una visi\u00f3n excepcional de sus capacidades de inspecci\u00f3n","datePublished":"2022-10-25T12:33:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/"},"wordCount":502,"publisher":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Thumbnail-for-videos-21.10.22-e1666363609594.jpg","keywords":["ai","innovation","renewableenergy","windenergy"],"articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/","url":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/","name":"Perceptual Robotics ofrece una visi\u00f3n excepcional de sus capacidades de inspecci\u00f3n - Perceptual Robotics","isPartOf":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/#primaryimage"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Thumbnail-for-videos-21.10.22-e1666363609594.jpg","datePublished":"2022-10-25T12:33:00+00:00","breadcrumb":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/#primaryimage","url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Thumbnail-for-videos-21.10.22-e1666363609594.jpg","contentUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2022\/10\/Thumbnail-for-videos-21.10.22-e1666363609594.jpg","width":1103,"height":601},{"@type":"BreadcrumbList","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-ofrece-una-vision-excepcional-de-sus-capacidades-de-inspeccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.perceptual-robotics.com\/es\/"},{"@type":"ListItem","position":2,"name":"Perceptual Robotics ofrece una visi\u00f3n excepcional de sus capacidades de inspecci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.perceptual-robotics.com\/es\/#website","url":"https:\/\/www.perceptual-robotics.com\/es\/","name":"Perceptual Robotics","description":"Automated wind turbine inspections","publisher":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.perceptual-robotics.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization","name":"Perceptual Robotics","url":"https:\/\/www.perceptual-robotics.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2021\/06\/home-video-poster.jpg","contentUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2021\/06\/home-video-poster.jpg","width":1280,"height":676,"caption":"Perceptual Robotics"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/perceptualrobotics\/","https:\/\/x.com\/Perc_Robotics","https:\/\/www.linkedin.com\/company\/perceptual-robotics\/","https:\/\/www.youtube.com\/channel\/UCZP4-T_Xl9xDRkdx6TEZEQw"]},{"@type":"Person","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/person\/fd287a03747dd732641469d987ba62f7","name":"Irenie Karachaliou","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f2dca6dc81392d476e9fda881d93b2920610bfe9bee5d282781b9fe8012c354?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f2dca6dc81392d476e9fda881d93b2920610bfe9bee5d282781b9fe8012c354?s=96&d=mm&r=g","caption":"Irenie Karachaliou"},"url":"https:\/\/www.perceptual-robotics.com\/es\/author\/ireniekarachaliou\/"}]}},"_links":{"self":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts\/83578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/comments?post=83578"}],"version-history":[{"count":2,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts\/83578\/revisions"}],"predecessor-version":[{"id":83580,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts\/83578\/revisions\/83580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/media\/83473"}],"wp:attachment":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/media?parent=83578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/categories?post=83578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/tags?post=83578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}