{"id":84318,"date":"2023-07-20T11:22:59","date_gmt":"2023-07-20T10:22:59","guid":{"rendered":"https:\/\/www.perceptual-robotics.com\/?p=84318"},"modified":"2023-07-20T11:22:59","modified_gmt":"2023-07-20T10:22:59","slug":"perceptual-robotics-welcomes-interns-to-the-team","status":"publish","type":"post","link":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/","title":{"rendered":"Perceptual Robotics welcomes interns to the team"},"content":{"rendered":"<p>Say hello to our new interns, Phil Blecher and Jakub Amin!<\/p>\n<p>We\u2019ve developed a strong partnership with @BristolUniversity and @UWEBristol over the past few years. With our office based on the UWE Bristol campus and our co-founders\u2019 all alumni of Bristol University, both universities have been an important part of our journey.<\/p>\n<p>This partnership has led to a range of valuable opportunities including various internships &#8211; with Phil and Jakub being our latest!<\/p>\n<p>Settling in quickly, they\u2019ve both embraced working as part of the drone team helping to develop and refine aspects of some of our hardware and software<\/p>\n<p>We look forward to witnessing their growth and achievements!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Say hello to our new interns, Phil Blecher and Jakub Amin!<\/p>\n","protected":false},"author":7,"featured_media":84319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[1],"tags":[168,169,123,91,31,22,35,29,30],"class_list":["post-84318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-interns","tag-internships","tag-perceptualrobotics","tag-robotics","tag-artificialintelligence","tag-blades","tag-innovation","tag-renewableenergy","tag-windenergy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Perceptual Robotics welcomes interns to the team - Perceptual Robotics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perceptual Robotics welcomes interns to the team - Perceptual Robotics\" \/>\n<meta property=\"og:description\" content=\"Say hello to our new interns, Phil Blecher and Jakub Amin!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/\" \/>\n<meta property=\"og:site_name\" content=\"Perceptual Robotics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/perceptualrobotics\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-20T10:22:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2023\/07\/new-interns.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irenie Karachaliou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Perc_Robotics\" \/>\n<meta name=\"twitter:site\" content=\"@Perc_Robotics\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irenie Karachaliou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perceptual Robotics welcomes interns to the team - Perceptual Robotics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/","og_locale":"es_ES","og_type":"article","og_title":"Perceptual Robotics welcomes interns to the team - Perceptual Robotics","og_description":"Say hello to our new interns, Phil Blecher and Jakub Amin!","og_url":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/","og_site_name":"Perceptual Robotics","article_publisher":"https:\/\/www.facebook.com\/perceptualrobotics\/","article_published_time":"2023-07-20T10:22:59+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2023\/07\/new-interns.jpg","type":"image\/jpeg"}],"author":"Irenie Karachaliou","twitter_card":"summary_large_image","twitter_creator":"@Perc_Robotics","twitter_site":"@Perc_Robotics","twitter_misc":{"Escrito por":"Irenie Karachaliou","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/#article","isPartOf":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/"},"author":{"name":"Irenie Karachaliou","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/person\/fd287a03747dd732641469d987ba62f7"},"headline":"Perceptual Robotics welcomes interns to the team","datePublished":"2023-07-20T10:22:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/"},"wordCount":118,"publisher":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2023\/07\/new-interns.jpg","keywords":["#interns","#internships","#perceptualrobotics","#robotics","artificialintelligence","blades","innovation","renewableenergy","windenergy"],"articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/","url":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/","name":"Perceptual Robotics welcomes interns to the team - Perceptual Robotics","isPartOf":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/#primaryimage"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2023\/07\/new-interns.jpg","datePublished":"2023-07-20T10:22:59+00:00","breadcrumb":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/#primaryimage","url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2023\/07\/new-interns.jpg","contentUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2023\/07\/new-interns.jpg","width":1920,"height":1280,"caption":"Phil Blecher and Jakub Amin with equipment"},{"@type":"BreadcrumbList","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-welcomes-interns-to-the-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.perceptual-robotics.com\/es\/"},{"@type":"ListItem","position":2,"name":"Perceptual Robotics welcomes interns to the team"}]},{"@type":"WebSite","@id":"https:\/\/www.perceptual-robotics.com\/es\/#website","url":"https:\/\/www.perceptual-robotics.com\/es\/","name":"Perceptual Robotics","description":"Automated wind turbine inspections","publisher":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.perceptual-robotics.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization","name":"Perceptual Robotics","url":"https:\/\/www.perceptual-robotics.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2021\/06\/home-video-poster.jpg","contentUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2021\/06\/home-video-poster.jpg","width":1280,"height":676,"caption":"Perceptual Robotics"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/perceptualrobotics\/","https:\/\/x.com\/Perc_Robotics","https:\/\/www.linkedin.com\/company\/perceptual-robotics\/","https:\/\/www.youtube.com\/channel\/UCZP4-T_Xl9xDRkdx6TEZEQw"]},{"@type":"Person","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/person\/fd287a03747dd732641469d987ba62f7","name":"Irenie Karachaliou","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f2dca6dc81392d476e9fda881d93b2920610bfe9bee5d282781b9fe8012c354?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f2dca6dc81392d476e9fda881d93b2920610bfe9bee5d282781b9fe8012c354?s=96&d=mm&r=g","caption":"Irenie Karachaliou"},"url":"https:\/\/www.perceptual-robotics.com\/es\/author\/ireniekarachaliou\/"}]}},"_links":{"self":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts\/84318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/comments?post=84318"}],"version-history":[{"count":1,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts\/84318\/revisions"}],"predecessor-version":[{"id":84321,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts\/84318\/revisions\/84321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/media\/84319"}],"wp:attachment":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/media?parent=84318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/categories?post=84318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/tags?post=84318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}