{"id":85628,"date":"2025-02-27T10:09:29","date_gmt":"2025-02-27T10:09:29","guid":{"rendered":"https:\/\/www.perceptual-robotics.com\/?p=85628"},"modified":"2025-02-27T10:09:29","modified_gmt":"2025-02-27T10:09:29","slug":"perceptual-robotics-is-heading-to-rimini-italy","status":"publish","type":"post","link":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/","title":{"rendered":"Perceptual Robotics is heading to Rimini, Italy! \ud83c\uddee\ud83c\uddf9"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">We\u2019re excited to share that Irenie Karachaliou will be representing Perceptual Robotics at KEY \u2013 The Energy Transition Expo in Rimini, Italy, in March!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">KEY is a leading event for renewable energy, bringing together industry professionals, innovators, and decision-makers driving the future of clean energy. If you\u2019re attending and want to discuss cutting-edge wind turbine inspections, AI-driven analytics, or how Dot and Eve can optimize your operations\u2014let\u2019s connect!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\ud83d\udccd Find Irenie at KEY<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">\ud83d\udcc5 March 05 -07, 2025<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">\ud83d\udce9 Reach out to schedule a meeting!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>We\u2019re excited to share that Irenie Karachaliou will be representing Perceptual Robotics at KEY \u2013 The Energy Transition Expo in Rimini, Italy, in March!<\/p>\n","protected":false},"author":7,"featured_media":85631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[1],"tags":[109,235,101,236,113,241,261,172,240,173,123,91,170,34,31,20,22,260,33,35,115,29,37],"class_list":["post-85628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-bladeinspections","tag-dhalion","tag-drone","tag-efficiencyunlocked","tag-energy","tag-industryinsights","tag-key2025","tag-offshorewindenergy","tag-operationalefficiency","tag-operations","tag-perceptualrobotics","tag-robotics","tag-uav","tag-ai","tag-artificialintelligence","tag-bladerepair","tag-blades","tag-customersupport","tag-droneinspection","tag-innovation","tag-offshorewind","tag-renewableenergy","tag-sustainability"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Perceptual Robotics is heading to Rimini, Italy! \ud83c\uddee\ud83c\uddf9 - Perceptual Robotics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perceptual Robotics is heading to Rimini, Italy! \ud83c\uddee\ud83c\uddf9 - Perceptual Robotics\" \/>\n<meta property=\"og:description\" content=\"We\u2019re excited to share that Irenie Karachaliou will be representing Perceptual Robotics at KEY \u2013 The Energy Transition Expo in Rimini, Italy, in March!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/\" \/>\n<meta property=\"og:site_name\" content=\"Perceptual Robotics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/perceptualrobotics\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-27T10:09:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2025\/02\/1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irenie Karachaliou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Perc_Robotics\" \/>\n<meta name=\"twitter:site\" content=\"@Perc_Robotics\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irenie Karachaliou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perceptual Robotics is heading to Rimini, Italy! \ud83c\uddee\ud83c\uddf9 - Perceptual Robotics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/","og_locale":"es_ES","og_type":"article","og_title":"Perceptual Robotics is heading to Rimini, Italy! \ud83c\uddee\ud83c\uddf9 - Perceptual Robotics","og_description":"We\u2019re excited to share that Irenie Karachaliou will be representing Perceptual Robotics at KEY \u2013 The Energy Transition Expo in Rimini, Italy, in March!","og_url":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/","og_site_name":"Perceptual Robotics","article_publisher":"https:\/\/www.facebook.com\/perceptualrobotics\/","article_published_time":"2025-02-27T10:09:29+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2025\/02\/1-1.jpg","type":"image\/jpeg"}],"author":"Irenie Karachaliou","twitter_card":"summary_large_image","twitter_creator":"@Perc_Robotics","twitter_site":"@Perc_Robotics","twitter_misc":{"Escrito por":"Irenie Karachaliou","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/#article","isPartOf":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/"},"author":{"name":"Irenie Karachaliou","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/person\/fd287a03747dd732641469d987ba62f7"},"headline":"Perceptual Robotics is heading to Rimini, Italy! \ud83c\uddee\ud83c\uddf9","datePublished":"2025-02-27T10:09:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/"},"wordCount":90,"publisher":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2025\/02\/1-1.jpg","keywords":["#bladeinspections","#Dhalion","#drone","#EfficiencyUnlocked","#energy","#IndustryInsights","#KEY2025","#offshorewindenergy","#OperationalEfficiency","#operations","#perceptualrobotics","#robotics","#uav","ai","artificialintelligence","bladerepair","blades","customersupport","droneinspection","innovation","offshorewind","renewableenergy","sustainability"],"articleSection":["Uncategorized"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/","url":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/","name":"Perceptual Robotics is heading to Rimini, Italy! \ud83c\uddee\ud83c\uddf9 - Perceptual Robotics","isPartOf":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/#primaryimage"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2025\/02\/1-1.jpg","datePublished":"2025-02-27T10:09:29+00:00","breadcrumb":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/#primaryimage","url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2025\/02\/1-1.jpg","contentUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2025\/02\/1-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.perceptual-robotics.com\/es\/perceptual-robotics-is-heading-to-rimini-italy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.perceptual-robotics.com\/es\/"},{"@type":"ListItem","position":2,"name":"Perceptual Robotics is heading to Rimini, Italy! \ud83c\uddee\ud83c\uddf9"}]},{"@type":"WebSite","@id":"https:\/\/www.perceptual-robotics.com\/es\/#website","url":"https:\/\/www.perceptual-robotics.com\/es\/","name":"Perceptual Robotics","description":"Automated wind turbine inspections","publisher":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.perceptual-robotics.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization","name":"Perceptual Robotics","url":"https:\/\/www.perceptual-robotics.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2021\/06\/home-video-poster.jpg","contentUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2021\/06\/home-video-poster.jpg","width":1280,"height":676,"caption":"Perceptual Robotics"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/perceptualrobotics\/","https:\/\/x.com\/Perc_Robotics","https:\/\/www.linkedin.com\/company\/perceptual-robotics\/","https:\/\/www.youtube.com\/channel\/UCZP4-T_Xl9xDRkdx6TEZEQw"]},{"@type":"Person","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/person\/fd287a03747dd732641469d987ba62f7","name":"Irenie Karachaliou","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f2dca6dc81392d476e9fda881d93b2920610bfe9bee5d282781b9fe8012c354?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f2dca6dc81392d476e9fda881d93b2920610bfe9bee5d282781b9fe8012c354?s=96&d=mm&r=g","caption":"Irenie Karachaliou"},"url":"https:\/\/www.perceptual-robotics.com\/es\/author\/ireniekarachaliou\/"}]}},"_links":{"self":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts\/85628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/comments?post=85628"}],"version-history":[{"count":1,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts\/85628\/revisions"}],"predecessor-version":[{"id":85633,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts\/85628\/revisions\/85633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/media\/85631"}],"wp:attachment":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/media?parent=85628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/categories?post=85628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/tags?post=85628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}