{"id":84,"count":0,"description":"","link":"https:\/\/www.perceptual-robotics.com\/es\/tag\/women-es\/","name":"women","slug":"women-es","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>women Archives - Perceptual Robotics<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"women Archives - Perceptual Robotics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.perceptual-robotics.com\/es\/tag\/women-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Perceptual Robotics\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2024\/09\/DJI_20240105153739_0019_V.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Perc_Robotics\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"women Archives - Perceptual Robotics","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"women Archives - Perceptual Robotics","og_url":"https:\/\/www.perceptual-robotics.com\/es\/tag\/women-es\/","og_site_name":"Perceptual Robotics","og_image":[{"width":1920,"height":1439,"url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2024\/09\/DJI_20240105153739_0019_V.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Perc_Robotics","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.perceptual-robotics.com\/es\/tag\/women-es\/","url":"https:\/\/www.perceptual-robotics.com\/es\/tag\/women-es\/","name":"women Archives - Perceptual Robotics","isPartOf":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/tag\/women-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.perceptual-robotics.com\/es\/tag\/women-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.perceptual-robotics.com\/es\/"},{"@type":"ListItem","position":2,"name":"women"}]},{"@type":"WebSite","@id":"https:\/\/www.perceptual-robotics.com\/es\/#website","url":"https:\/\/www.perceptual-robotics.com\/es\/","name":"Perceptual Robotics","description":"Automated wind turbine inspections","publisher":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.perceptual-robotics.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.perceptual-robotics.com\/es\/#organization","name":"Perceptual Robotics","url":"https:\/\/www.perceptual-robotics.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2021\/06\/home-video-poster.jpg","contentUrl":"https:\/\/www.perceptual-robotics.com\/wp-content\/uploads\/2021\/06\/home-video-poster.jpg","width":1280,"height":676,"caption":"Perceptual Robotics"},"image":{"@id":"https:\/\/www.perceptual-robotics.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/perceptualrobotics\/","https:\/\/x.com\/Perc_Robotics","https:\/\/www.linkedin.com\/company\/perceptual-robotics\/","https:\/\/www.youtube.com\/channel\/UCZP4-T_Xl9xDRkdx6TEZEQw"]}]}},"_links":{"self":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/tags\/84","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.perceptual-robotics.com\/es\/wp-json\/wp\/v2\/posts?tags=84"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}